{"id":1333,"date":"2024-06-06T14:28:55","date_gmt":"2024-06-06T12:28:55","guid":{"rendered":"http:\/\/new.aecagroup.com\/?p=1333"},"modified":"2024-11-19T13:40:39","modified_gmt":"2024-11-19T12:40:39","slug":"instal%c2%b7lacio-fotovoltaica-dautoconsum-per-a-un-client-del-port-de-barcelona","status":"publish","type":"post","link":"https:\/\/aecagroup.com\/ca\/instal%c2%b7lacio-fotovoltaica-dautoconsum-per-a-un-client-del-port-de-barcelona\/","title":{"rendered":"Instal\u00b7laci\u00f3 fotovoltaica d&#8217;Autoconsum per a un client del Port de Barcelona"},"content":{"rendered":"<p>Finalitzada una instal\u00b7laci\u00f3 fotovoltaica d&#8217;Autoconsum per a un client del Port de Barcelona, un treball d&#8217;altura, a 40 metres, en unes sitges de dip\u00f2sit.<\/p>\n<p>90 m\u00f2duls de *445Wp que generen 36,*45kWp i un inversor *Ingeteam *3play de *33kW per a gestionar la producci\u00f3 de m\u00e9s de 48.*000kWh a l&#8217;any, la qual cosa representa una reducci\u00f3 de CO\u2082 en m\u00e9s de 19T.<\/p>\n<p>Treballem amb els nostres clients col\u00b7laborant en els seus projecte de respecte al Medi Ambient.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-medium wp-image-3222\" src=\"https:\/\/aecagroup.com\/wp-content\/uploads\/2021\/03\/1614669300921-1-282x300.jpg\" alt=\"Instal\u00b7laci\u00f3 fotovoltaica d'Autoconsum per a un client del Port de Barcelona\" width=\"282\" height=\"300\" \/><\/p>\n<p>#autoconsum #*comunidadporelcambio<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Finalitzada una instal\u00b7laci\u00f3 fotovoltaica d&#8217;Autoconsum per a un client del Port de Barcelona, un treball d&#8217;altura, a 40 metres, en unes sitges de dip\u00f2sit. 90 m\u00f2duls de *445Wp que generen 36,*45kWp i un inversor *Ingeteam *3play de *33kW per a gestionar la producci\u00f3 de m\u00e9s de 48.*000kWh a l&#8217;any, la qual cosa representa una reducci\u00f3 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[30,28,26],"tags":[],"class_list":["post-1333","post","type-post","status-publish","format-standard","hentry","category-energies-renovables","category-experiencies","category-sostenibilitat"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Instal\u00b7laci\u00f3 fotovoltaica d&#039;Autoconsum per a un client del Port de Barcelona - Aeca Group<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aecagroup.com\/ca\/instal%c2%b7lacio-fotovoltaica-dautoconsum-per-a-un-client-del-port-de-barcelona\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Instal\u00b7laci\u00f3 fotovoltaica d&#039;Autoconsum per a un client del Port de Barcelona - Aeca Group\" \/>\n<meta property=\"og:description\" content=\"Finalitzada una instal\u00b7laci\u00f3 fotovoltaica d&#8217;Autoconsum per a un client del Port de Barcelona, un treball d&#8217;altura, a 40 metres, en unes sitges de dip\u00f2sit. 90 m\u00f2duls de *445Wp que generen 36,*45kWp i un inversor *Ingeteam *3play de *33kW per a gestionar la producci\u00f3 de m\u00e9s de 48.*000kWh a l&#8217;any, la qual cosa representa una reducci\u00f3 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aecagroup.com\/ca\/instal%c2%b7lacio-fotovoltaica-dautoconsum-per-a-un-client-del-port-de-barcelona\/\" \/>\n<meta property=\"og:site_name\" content=\"Aeca Group\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-06T12:28:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-19T12:40:39+00:00\" \/>\n<meta name=\"author\" content=\"sinapsis\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"sinapsis\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/aecagroup.com\\\/ca\\\/instal%c2%b7lacio-fotovoltaica-dautoconsum-per-a-un-client-del-port-de-barcelona\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aecagroup.com\\\/ca\\\/instal%c2%b7lacio-fotovoltaica-dautoconsum-per-a-un-client-del-port-de-barcelona\\\/\"},\"author\":{\"name\":\"sinapsis\",\"@id\":\"https:\\\/\\\/aecagroup.com\\\/ca\\\/#\\\/schema\\\/person\\\/57abb84aa11b97c637ffd93e6905ac6f\"},\"headline\":\"Instal\u00b7laci\u00f3 fotovoltaica d&#8217;Autoconsum per a un client del Port de Barcelona\",\"datePublished\":\"2024-06-06T12:28:55+00:00\",\"dateModified\":\"2024-11-19T12:40:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/aecagroup.com\\\/ca\\\/instal%c2%b7lacio-fotovoltaica-dautoconsum-per-a-un-client-del-port-de-barcelona\\\/\"},\"wordCount\":98,\"publisher\":{\"@id\":\"https:\\\/\\\/aecagroup.com\\\/ca\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/aecagroup.com\\\/ca\\\/instal%c2%b7lacio-fotovoltaica-dautoconsum-per-a-un-client-del-port-de-barcelona\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aecagroup.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/1614669300921-1-282x300.jpg\",\"articleSection\":[\"Energies renovables\",\"Experi\u00e8ncies\",\"Sostenibilitat\"],\"inLanguage\":\"ca\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aecagroup.com\\\/ca\\\/instal%c2%b7lacio-fotovoltaica-dautoconsum-per-a-un-client-del-port-de-barcelona\\\/\",\"url\":\"https:\\\/\\\/aecagroup.com\\\/ca\\\/instal%c2%b7lacio-fotovoltaica-dautoconsum-per-a-un-client-del-port-de-barcelona\\\/\",\"name\":\"Instal\u00b7laci\u00f3 fotovoltaica d'Autoconsum per a un client del Port de Barcelona - Aeca Group\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aecagroup.com\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/aecagroup.com\\\/ca\\\/instal%c2%b7lacio-fotovoltaica-dautoconsum-per-a-un-client-del-port-de-barcelona\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/aecagroup.com\\\/ca\\\/instal%c2%b7lacio-fotovoltaica-dautoconsum-per-a-un-client-del-port-de-barcelona\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aecagroup.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/1614669300921-1-282x300.jpg\",\"datePublished\":\"2024-06-06T12:28:55+00:00\",\"dateModified\":\"2024-11-19T12:40:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aecagroup.com\\\/ca\\\/instal%c2%b7lacio-fotovoltaica-dautoconsum-per-a-un-client-del-port-de-barcelona\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aecagroup.com\\\/ca\\\/instal%c2%b7lacio-fotovoltaica-dautoconsum-per-a-un-client-del-port-de-barcelona\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/aecagroup.com\\\/ca\\\/instal%c2%b7lacio-fotovoltaica-dautoconsum-per-a-un-client-del-port-de-barcelona\\\/#primaryimage\",\"url\":\"https:\\\/\\\/aecagroup.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/1614669300921-1-282x300.jpg\",\"contentUrl\":\"https:\\\/\\\/aecagroup.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/1614669300921-1-282x300.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aecagroup.com\\\/ca\\\/instal%c2%b7lacio-fotovoltaica-dautoconsum-per-a-un-client-del-port-de-barcelona\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/aecagroup.com\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Instal\u00b7laci\u00f3 fotovoltaica d&#8217;Autoconsum per a un client del Port de Barcelona\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aecagroup.com\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/aecagroup.com\\\/ca\\\/\",\"name\":\"Aeca Group\",\"description\":\"Solucions Energ\u00e8tiques\",\"publisher\":{\"@id\":\"https:\\\/\\\/aecagroup.com\\\/ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aecagroup.com\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/aecagroup.com\\\/ca\\\/#organization\",\"name\":\"Aeca Group\",\"url\":\"https:\\\/\\\/aecagroup.com\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/aecagroup.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/aecagroup.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Logo_AECA_2020_-_catala.webp\",\"contentUrl\":\"https:\\\/\\\/aecagroup.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Logo_AECA_2020_-_catala.webp\",\"width\":1565,\"height\":622,\"caption\":\"Aeca Group\"},\"image\":{\"@id\":\"https:\\\/\\\/aecagroup.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/aecagroup.com\\\/ca\\\/#\\\/schema\\\/person\\\/57abb84aa11b97c637ffd93e6905ac6f\",\"name\":\"sinapsis\",\"sameAs\":[\"http:\\\/\\\/new.aecagroup.com\"],\"url\":\"https:\\\/\\\/aecagroup.com\\\/ca\\\/author\\\/sinapsis\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Instal\u00b7laci\u00f3 fotovoltaica d'Autoconsum per a un client del Port de Barcelona - Aeca Group","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aecagroup.com\/ca\/instal%c2%b7lacio-fotovoltaica-dautoconsum-per-a-un-client-del-port-de-barcelona\/","og_locale":"ca_ES","og_type":"article","og_title":"Instal\u00b7laci\u00f3 fotovoltaica d'Autoconsum per a un client del Port de Barcelona - Aeca Group","og_description":"Finalitzada una instal\u00b7laci\u00f3 fotovoltaica d&#8217;Autoconsum per a un client del Port de Barcelona, un treball d&#8217;altura, a 40 metres, en unes sitges de dip\u00f2sit. 90 m\u00f2duls de *445Wp que generen 36,*45kWp i un inversor *Ingeteam *3play de *33kW per a gestionar la producci\u00f3 de m\u00e9s de 48.*000kWh a l&#8217;any, la qual cosa representa una reducci\u00f3 [&hellip;]","og_url":"https:\/\/aecagroup.com\/ca\/instal%c2%b7lacio-fotovoltaica-dautoconsum-per-a-un-client-del-port-de-barcelona\/","og_site_name":"Aeca Group","article_published_time":"2024-06-06T12:28:55+00:00","article_modified_time":"2024-11-19T12:40:39+00:00","author":"sinapsis","twitter_card":"summary_large_image","twitter_misc":{"Written by":"sinapsis","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/aecagroup.com\/ca\/instal%c2%b7lacio-fotovoltaica-dautoconsum-per-a-un-client-del-port-de-barcelona\/#article","isPartOf":{"@id":"https:\/\/aecagroup.com\/ca\/instal%c2%b7lacio-fotovoltaica-dautoconsum-per-a-un-client-del-port-de-barcelona\/"},"author":{"name":"sinapsis","@id":"https:\/\/aecagroup.com\/ca\/#\/schema\/person\/57abb84aa11b97c637ffd93e6905ac6f"},"headline":"Instal\u00b7laci\u00f3 fotovoltaica d&#8217;Autoconsum per a un client del Port de Barcelona","datePublished":"2024-06-06T12:28:55+00:00","dateModified":"2024-11-19T12:40:39+00:00","mainEntityOfPage":{"@id":"https:\/\/aecagroup.com\/ca\/instal%c2%b7lacio-fotovoltaica-dautoconsum-per-a-un-client-del-port-de-barcelona\/"},"wordCount":98,"publisher":{"@id":"https:\/\/aecagroup.com\/ca\/#organization"},"image":{"@id":"https:\/\/aecagroup.com\/ca\/instal%c2%b7lacio-fotovoltaica-dautoconsum-per-a-un-client-del-port-de-barcelona\/#primaryimage"},"thumbnailUrl":"https:\/\/aecagroup.com\/wp-content\/uploads\/2021\/03\/1614669300921-1-282x300.jpg","articleSection":["Energies renovables","Experi\u00e8ncies","Sostenibilitat"],"inLanguage":"ca"},{"@type":"WebPage","@id":"https:\/\/aecagroup.com\/ca\/instal%c2%b7lacio-fotovoltaica-dautoconsum-per-a-un-client-del-port-de-barcelona\/","url":"https:\/\/aecagroup.com\/ca\/instal%c2%b7lacio-fotovoltaica-dautoconsum-per-a-un-client-del-port-de-barcelona\/","name":"Instal\u00b7laci\u00f3 fotovoltaica d'Autoconsum per a un client del Port de Barcelona - Aeca Group","isPartOf":{"@id":"https:\/\/aecagroup.com\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/aecagroup.com\/ca\/instal%c2%b7lacio-fotovoltaica-dautoconsum-per-a-un-client-del-port-de-barcelona\/#primaryimage"},"image":{"@id":"https:\/\/aecagroup.com\/ca\/instal%c2%b7lacio-fotovoltaica-dautoconsum-per-a-un-client-del-port-de-barcelona\/#primaryimage"},"thumbnailUrl":"https:\/\/aecagroup.com\/wp-content\/uploads\/2021\/03\/1614669300921-1-282x300.jpg","datePublished":"2024-06-06T12:28:55+00:00","dateModified":"2024-11-19T12:40:39+00:00","breadcrumb":{"@id":"https:\/\/aecagroup.com\/ca\/instal%c2%b7lacio-fotovoltaica-dautoconsum-per-a-un-client-del-port-de-barcelona\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aecagroup.com\/ca\/instal%c2%b7lacio-fotovoltaica-dautoconsum-per-a-un-client-del-port-de-barcelona\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/aecagroup.com\/ca\/instal%c2%b7lacio-fotovoltaica-dautoconsum-per-a-un-client-del-port-de-barcelona\/#primaryimage","url":"https:\/\/aecagroup.com\/wp-content\/uploads\/2021\/03\/1614669300921-1-282x300.jpg","contentUrl":"https:\/\/aecagroup.com\/wp-content\/uploads\/2021\/03\/1614669300921-1-282x300.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/aecagroup.com\/ca\/instal%c2%b7lacio-fotovoltaica-dautoconsum-per-a-un-client-del-port-de-barcelona\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/aecagroup.com\/ca\/"},{"@type":"ListItem","position":2,"name":"Instal\u00b7laci\u00f3 fotovoltaica d&#8217;Autoconsum per a un client del Port de Barcelona"}]},{"@type":"WebSite","@id":"https:\/\/aecagroup.com\/ca\/#website","url":"https:\/\/aecagroup.com\/ca\/","name":"Aeca Group","description":"Solucions Energ\u00e8tiques","publisher":{"@id":"https:\/\/aecagroup.com\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aecagroup.com\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/aecagroup.com\/ca\/#organization","name":"Aeca Group","url":"https:\/\/aecagroup.com\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/aecagroup.com\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/aecagroup.com\/wp-content\/uploads\/2024\/09\/Logo_AECA_2020_-_catala.webp","contentUrl":"https:\/\/aecagroup.com\/wp-content\/uploads\/2024\/09\/Logo_AECA_2020_-_catala.webp","width":1565,"height":622,"caption":"Aeca Group"},"image":{"@id":"https:\/\/aecagroup.com\/ca\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/aecagroup.com\/ca\/#\/schema\/person\/57abb84aa11b97c637ffd93e6905ac6f","name":"sinapsis","sameAs":["http:\/\/new.aecagroup.com"],"url":"https:\/\/aecagroup.com\/ca\/author\/sinapsis\/"}]}},"_links":{"self":[{"href":"https:\/\/aecagroup.com\/ca\/wp-json\/wp\/v2\/posts\/1333","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aecagroup.com\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aecagroup.com\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aecagroup.com\/ca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aecagroup.com\/ca\/wp-json\/wp\/v2\/comments?post=1333"}],"version-history":[{"count":1,"href":"https:\/\/aecagroup.com\/ca\/wp-json\/wp\/v2\/posts\/1333\/revisions"}],"predecessor-version":[{"id":1334,"href":"https:\/\/aecagroup.com\/ca\/wp-json\/wp\/v2\/posts\/1333\/revisions\/1334"}],"wp:attachment":[{"href":"https:\/\/aecagroup.com\/ca\/wp-json\/wp\/v2\/media?parent=1333"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aecagroup.com\/ca\/wp-json\/wp\/v2\/categories?post=1333"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aecagroup.com\/ca\/wp-json\/wp\/v2\/tags?post=1333"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}