{"id":29,"count":10,"description":"","link":"https:\/\/aecagroup.com\/ca\/category\/assessorament-energetic\/","name":"Assessorament energ\u00e8tic","slug":"assessorament-energetic","taxonomy":"category","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Assessorament energ\u00e8tic archivos - Aeca Group<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aecagroup.com\/ca\/category\/assessorament-energetic\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Assessorament energ\u00e8tic archivos - Aeca Group\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aecagroup.com\/ca\/category\/assessorament-energetic\/\" \/>\n<meta property=\"og:site_name\" content=\"Aeca Group\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/aecagroup.com\\\/ca\\\/category\\\/assessorament-energetic\\\/\",\"url\":\"https:\\\/\\\/aecagroup.com\\\/ca\\\/category\\\/assessorament-energetic\\\/\",\"name\":\"Assessorament energ\u00e8tic archivos - Aeca Group\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aecagroup.com\\\/ca\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aecagroup.com\\\/ca\\\/category\\\/assessorament-energetic\\\/#breadcrumb\"},\"inLanguage\":\"ca\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aecagroup.com\\\/ca\\\/category\\\/assessorament-energetic\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/aecagroup.com\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Assessorament energ\u00e8tic\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aecagroup.com\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/aecagroup.com\\\/ca\\\/\",\"name\":\"Aeca Group\",\"description\":\"Solucions Energ\u00e8tiques\",\"publisher\":{\"@id\":\"https:\\\/\\\/aecagroup.com\\\/ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aecagroup.com\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/aecagroup.com\\\/ca\\\/#organization\",\"name\":\"Aeca Group\",\"url\":\"https:\\\/\\\/aecagroup.com\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/aecagroup.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/aecagroup.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Logo_AECA_2020_-_catala.webp\",\"contentUrl\":\"https:\\\/\\\/aecagroup.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Logo_AECA_2020_-_catala.webp\",\"width\":1565,\"height\":622,\"caption\":\"Aeca Group\"},\"image\":{\"@id\":\"https:\\\/\\\/aecagroup.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Assessorament energ\u00e8tic archivos - Aeca Group","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aecagroup.com\/ca\/category\/assessorament-energetic\/","og_locale":"ca_ES","og_type":"article","og_title":"Assessorament energ\u00e8tic archivos - Aeca Group","og_url":"https:\/\/aecagroup.com\/ca\/category\/assessorament-energetic\/","og_site_name":"Aeca Group","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/aecagroup.com\/ca\/category\/assessorament-energetic\/","url":"https:\/\/aecagroup.com\/ca\/category\/assessorament-energetic\/","name":"Assessorament energ\u00e8tic archivos - Aeca Group","isPartOf":{"@id":"https:\/\/aecagroup.com\/ca\/#website"},"breadcrumb":{"@id":"https:\/\/aecagroup.com\/ca\/category\/assessorament-energetic\/#breadcrumb"},"inLanguage":"ca"},{"@type":"BreadcrumbList","@id":"https:\/\/aecagroup.com\/ca\/category\/assessorament-energetic\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/aecagroup.com\/ca\/"},{"@type":"ListItem","position":2,"name":"Assessorament energ\u00e8tic"}]},{"@type":"WebSite","@id":"https:\/\/aecagroup.com\/ca\/#website","url":"https:\/\/aecagroup.com\/ca\/","name":"Aeca Group","description":"Solucions Energ\u00e8tiques","publisher":{"@id":"https:\/\/aecagroup.com\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aecagroup.com\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/aecagroup.com\/ca\/#organization","name":"Aeca Group","url":"https:\/\/aecagroup.com\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/aecagroup.com\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/aecagroup.com\/wp-content\/uploads\/2024\/09\/Logo_AECA_2020_-_catala.webp","contentUrl":"https:\/\/aecagroup.com\/wp-content\/uploads\/2024\/09\/Logo_AECA_2020_-_catala.webp","width":1565,"height":622,"caption":"Aeca Group"},"image":{"@id":"https:\/\/aecagroup.com\/ca\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/aecagroup.com\/ca\/wp-json\/wp\/v2\/categories\/29","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aecagroup.com\/ca\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/aecagroup.com\/ca\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/aecagroup.com\/ca\/wp-json\/wp\/v2\/posts?categories=29"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}